{"id":11662,"date":"2018-11-08T09:57:06","date_gmt":"2018-11-08T14:57:06","guid":{"rendered":"https:\/\/www.cae.net\/?p=11662"},"modified":"2025-07-24T13:26:53","modified_gmt":"2025-07-24T11:26:53","slug":"microaprendizaje-el-aprendizaje-del-s-xxi","status":"publish","type":"post","link":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/","title":{"rendered":"Microaprendizaje: el aprendizaje del s.XXI"},"content":{"rendered":"<div style=\"text-align: justify;\">\n<p>Desde hace unos a\u00f1os se habla de metodolog\u00edas innovadoras como el eLearning, la gamificaci\u00f3n o el <strong>microaprendizaje<\/strong>. Esta \u00faltima es una estrategia educativa que se caracteriza por <strong>la brevedad de las lecciones<\/strong>. Surgi\u00f3 en la primera d\u00e9cada del siglo XXI, y desde entonces se ha desarrollado enormemente. Se ha ido combinando con otras metodolog\u00edas y est\u00e1 explorando y explotando todos los beneficios que las <strong>plataformas e-learning<\/strong> suponen para este tipo de actividades interactivas.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6257\" title=\"Microaprendizaje\" src=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas-1024x572.jpg\" alt=\"cursos online informatica empresas\" width=\"1024\" height=\"572\" srcset=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg 1024w, https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas-400x223.jpg 400w, https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas-300x168.jpg 300w, https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas-768x429.jpg 768w, https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas-610x341.jpg 610w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>La inmersi\u00f3n de la tecnolog\u00eda en el aula<\/strong> ha supuesto un giro revolucionario en la forma de aprender. Ha roto con metodolog\u00edas tradicionales y se ha metido de lleno en los procesos de ense\u00f1anza. Ha incorporado<strong> nuevas f\u00f3rmulas <\/strong>que no solo son efectivas, sino que hacen de este proceso algo ameno y memorable tanto para alumnos como para profesores.<\/p>\n<h2><\/h2>\n<h3>\u00bfPor qu\u00e9 las plataformas e-learning son clave para el microaprendizaje?<\/h3>\n<p>Porque en este m\u00e9todo las actividades se ejecutan en un m\u00e1ximo de 15 minutos. Son peque\u00f1as <strong>p\u00edldoras formativas<\/strong> que permiten al alumno completar r\u00e1pidamente las lagunas que tengan en ciertas habilidades y conocimientos.<\/p>\n<p>Con las plataformas e-learning este tipo de p\u00edldoras se traducen en <strong>actividades din\u00e1micas, interactivas y gamificadas.<\/strong> El alumno aprende como si de un juego se tratase, y avanza a gran velocidad por los contenidos del temario.<\/p>\n<h2><\/h2>\n<h3>\u00bfPor qu\u00e9 es el aprendizaje del s. XXI?<\/h3>\n<p>En una sociedad como la nuestra, donde nos falta el tiempo para todo, el disponer de este tipo de actividades supone poder seguir un <strong>ritmo de aprendizaje personalizado<\/strong>. El cerebro humano puede procesar unos cuatro bits de informaci\u00f3n a la vez, con lo <strong>cual los resultados del aprendizaje con este enfoque son casi inmediatos<\/strong>.<\/p>\n<p>Esta metodolog\u00eda encaja a la perfecci\u00f3n en el <strong>mundo corporativo<\/strong>, pues potencia el conocimiento y por tanto aumenta la productividad de los equipos humanos de forma r\u00e1pida.<\/p>\n<h3><\/h3>\n<h3>\u00bfC\u00f3mo son los <a title=\"Recursos para una exitosa gamificaci\u00f3n\" href=\"https:\/\/www.dexway.com\/es\/recursos-para-una-gamificacion-en-el-aula-de-idiomas-exitosa\/\">ejercicios de microaprendizaje<\/a>?<\/h3>\n<p>Las llamamos c\u00e1psulas o p\u00edldoras. Se caracterizan por su <strong>brevedad, granularidad y variedad<\/strong>. En tan solo unos segundos, o como m\u00e1ximo en 15 minutos, el alumno tiene acceso a ejercicios enfocados a un tema en concreto (granularidad), concepto o idea.<\/p>\n<p>El contenido de las actividades de microaprendizaje puede tener formatos muy diversos: <strong>actividades interactivas, juegos, v\u00eddeos, preguntas, diapositivas, lecturas\u2026<\/strong> Esto es muy positivo porque no solo se adaptan al alumno en cuanto al tiempo de estudio, sino que <strong>podr\u00e1 recurrir al formato que m\u00e1s se adapte a sus preferencias<\/strong>. Hay quien aprende mejor viendo un libro o leyendo un texto, o interactuando con la actividad.<\/p>\n<p>El uso de la tecnolog\u00eda es lo que aporta esta <strong>flexibilidad para el alumno<\/strong>. Tienen la informaci\u00f3n disponible \u201caqu\u00ed y ahora\u201d. <strong>Los contenidos se adaptan a los dispositivos que utilizan<\/strong> (m\u00f3vil, tableta u ordenador) y, en el caso de las plataformas Dexway, su progreso se mantiene actualizado, por lo que pueden cambiar de dispositivo siempre que lo deseen.<\/p>\n<p>Adem\u00e1s, el hecho de que los ejercicios se centren en temas muy concretos<strong>, facilita su etiquetado y permite hacer b\u00fasquedas m\u00e1s r\u00e1pidas<\/strong>.<\/p>\n<h3><\/h3>\n<h3>\u00bfCu\u00e1les son las ventajas del microaprendizaje aplicado en los <a title=\"Dist\u00edngase de sus competidores\" href=\"https:\/\/www.dexway.com\/es\/como-distinguirse-competidores-con-sus-propios-cursos-dexway\/\">cursos Dexway<\/a>?<\/h3>\n<p><strong>#1. Resultados de aprendizaje eficaces e inmediatos. <\/strong>Los cursos Dexway se estructuran en diferentes unidades con diferentes lecciones dentro de ellas que trabajan conceptos espec\u00edficos.<\/p>\n<p><strong>#2. El alumno marca su propio ritmo. <\/strong>El propio alumno puede avanzar en el curso en funci\u00f3n de sus necesidades. Dispone de un calendario en el que marcar los d\u00edas que quiere trabajar y las lecciones a realizar.<\/p>\n<p><strong>#3. P\u00edldoras de contenido etiquetadas que aceleran las b\u00fasquedas. <\/strong>La ventaja frente a otros competidores es que en los cursos Dexway se encuentran contenidos propios y personalizados. El alumno podr\u00e1 acceder incluso a ejercicios de refuerzo para trabajar los objetivos que necesite.<\/p>\n<p><strong>#4. Contenidos accesibles en cualquier momento. <\/strong>Todos nuestros cursos son multiplataforma, por lo que el alumno podr\u00e1 acceder a los contenidos desde el dispositivo que desee, en el momento que desee, manteniendo su progreso actualizado en todos ellos.<\/p>\n<p><strong>#5. Diversos formatos para cubrir diversos estilos de aprendizaje. <\/strong>A lo largo de las lecciones el alumno se encontrar\u00e1 con diferentes tipos de ejercicios interactivos. El profesor podr\u00e1 adem\u00e1s modificar y ajustar estos ejercicios gracias a nuestra herramienta Authoring Tool.<\/p>\n<p><strong>#6. Aprendizaje din\u00e1mico e interactivo que facilita la interiorizaci\u00f3n de los contenidos.<\/strong> La gran variedad de ejercicios de los cursos Dexway hacen de nuestra metodolog\u00eda una de las m\u00e1s competentes del mercado.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el microaprendizaje las actividades se ejecutan en un m\u00e1ximo de 15 minutos. Son peque\u00f1as p\u00edldoras formativas que permiten al alumno completar r\u00e1pidamente los objetivos.<\/p>\n","protected":false},"author":2,"featured_media":6257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-cae"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>microaprendizaje aprendizaje siglo xxi ejercicios rapidos<\/title>\n<meta name=\"description\" content=\"En el microaprendizaje las actividades duran un m\u00e1ximo de 15 minutos. Permiten al alumno completar r\u00e1pidamente los objetivos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"microaprendizaje aprendizaje siglo xxi ejercicios rapidos\" \/>\n<meta property=\"og:description\" content=\"En el microaprendizaje las actividades duran un m\u00e1ximo de 15 minutos. Permiten al alumno completar r\u00e1pidamente los objetivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/\" \/>\n<meta property=\"og:site_name\" content=\"CAE Computer Aided E-learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elearning.cae\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-08T14:57:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T11:26:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:site\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/\"},\"author\":{\"name\":\"Communication\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"headline\":\"Microaprendizaje: el aprendizaje del s.XXI\",\"datePublished\":\"2018-11-08T14:57:06+00:00\",\"dateModified\":\"2025-07-24T11:26:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/\"},\"wordCount\":763,\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/cursos-online-informatica-empresas.jpg\",\"articleSection\":[\"Blog CAE\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/\",\"name\":\"microaprendizaje aprendizaje siglo xxi ejercicios rapidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/cursos-online-informatica-empresas.jpg\",\"datePublished\":\"2018-11-08T14:57:06+00:00\",\"dateModified\":\"2025-07-24T11:26:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"description\":\"En el microaprendizaje las actividades duran un m\u00e1ximo de 15 minutos. Permiten al alumno completar r\u00e1pidamente los objetivos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/cursos-online-informatica-empresas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/cursos-online-informatica-empresas.jpg\",\"width\":1024,\"height\":572,\"caption\":\"cursos online informatica empresas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/microaprendizaje-el-aprendizaje-del-s-xxi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microaprendizaje: el aprendizaje del s.XXI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\",\"name\":\"CAE Computer Aided E-learning\",\"description\":\"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cae.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\",\"name\":\"Communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"caption\":\"Communication\"},\"sameAs\":[\"http:\\\/\\\/www.cae.net\"],\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/author\\\/carmen-d-rosell-e-learning-specialist\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"microaprendizaje aprendizaje siglo xxi ejercicios rapidos","description":"En el microaprendizaje las actividades duran un m\u00e1ximo de 15 minutos. Permiten al alumno completar r\u00e1pidamente los objetivos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/","og_locale":"es_ES","og_type":"article","og_title":"microaprendizaje aprendizaje siglo xxi ejercicios rapidos","og_description":"En el microaprendizaje las actividades duran un m\u00e1ximo de 15 minutos. Permiten al alumno completar r\u00e1pidamente los objetivos.","og_url":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/","og_site_name":"CAE Computer Aided E-learning","article_publisher":"https:\/\/www.facebook.com\/elearning.cae","article_published_time":"2018-11-08T14:57:06+00:00","article_modified_time":"2025-07-24T11:26:53+00:00","og_image":[{"width":1024,"height":572,"url":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg","type":"image\/jpeg"}],"author":"Communication","twitter_card":"summary_large_image","twitter_creator":"@elearning_cae","twitter_site":"@elearning_cae","twitter_misc":{"Escrito por":"Communication","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/#article","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/"},"author":{"name":"Communication","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"headline":"Microaprendizaje: el aprendizaje del s.XXI","datePublished":"2018-11-08T14:57:06+00:00","dateModified":"2025-07-24T11:26:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/"},"wordCount":763,"image":{"@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg","articleSection":["Blog CAE"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/","url":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/","name":"microaprendizaje aprendizaje siglo xxi ejercicios rapidos","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/#primaryimage"},"image":{"@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg","datePublished":"2018-11-08T14:57:06+00:00","dateModified":"2025-07-24T11:26:53+00:00","author":{"@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"description":"En el microaprendizaje las actividades duran un m\u00e1ximo de 15 minutos. Permiten al alumno completar r\u00e1pidamente los objetivos.","breadcrumb":{"@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/#primaryimage","url":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg","contentUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/07\/cursos-online-informatica-empresas.jpg","width":1024,"height":572,"caption":"cursos online informatica empresas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cae.net\/es\/microaprendizaje-el-aprendizaje-del-s-xxi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cae.net\/es\/"},{"@type":"ListItem","position":2,"name":"Microaprendizaje: el aprendizaje del s.XXI"}]},{"@type":"WebSite","@id":"https:\/\/www.cae.net\/es\/#website","url":"https:\/\/www.cae.net\/es\/","name":"CAE Computer Aided E-learning","description":"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cae.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad","name":"Communication","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","caption":"Communication"},"sameAs":["http:\/\/www.cae.net"],"url":"https:\/\/www.cae.net\/es\/author\/carmen-d-rosell-e-learning-specialist\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/11662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/comments?post=11662"}],"version-history":[{"count":0,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/11662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/media\/6257"}],"wp:attachment":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/media?parent=11662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/categories?post=11662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/tags?post=11662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}