{"id":1519,"date":"2015-07-24T09:59:10","date_gmt":"2015-07-24T09:59:10","guid":{"rendered":"https:\/\/www.cae.net\/?p=1519"},"modified":"2025-11-28T14:35:09","modified_gmt":"2025-11-28T13:35:09","slug":"desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional","status":"publish","type":"post","link":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/","title":{"rendered":"Una soluci\u00f3n educativa para una universidad p\u00fablica internacional"},"content":{"rendered":"<h3>EL RETO<\/h3>\n<p>La necesidad part\u00eda de una universidad p\u00fablica con vocaci\u00f3n internacional, que apuesta por el conocimiento y la innovaci\u00f3n para lograr sus objetivos de calidad en la docencia. Est\u00e1 universidad imparte 81 titulaciones de grado, m\u00e1steres, doctorados y seminarios, muchos de ellos en lengua inglesa, recibe una media de 5000 estudiantes internacionales cada a\u00f1o y un amplio n\u00famero de locales interesados en compatibilizar sus estudios de grado con el desarrollo de sus habilidades y conocimientos en un segundo idioma. Dentro de este contexto su objetivo era crear una oferta en idiomas que incluyera cursos online en diferentes lenguas, as\u00ed como un centro de aprendizaje de lenguas o campus virtual que permitiera un aprendizaje participativo 3.0 a los estudiantes interesados en mejorar sus competencias ling\u00fc\u00edsticas en una segunda lengua.<\/p>\n<h3>LA\u00a0SOLUCI\u00d3N<\/h3>\n<p>Despu\u00e9s de llevar a cabo un estudio exhaustivo de las necesidades del cliente y del laboratorio de idiomas del que dispon\u00eda el campus universitario, CAE dise\u00f1\u00f3 un paquete de soluciones espec\u00edficas para el aprendizaje de idiomas en ingl\u00e9s (brit\u00e1nico y americano), franc\u00e9s, alem\u00e1n y espa\u00f1ol. Este plan de estudios inclu\u00eda las siguientes soluciones Dexway: <strong>cursos online Dexway Academy (V3)<\/strong> combinados con <strong>Dexway classroom teacher<\/strong>. Estos cursos constan de cinco niveles, desde A1 hasta C1, cada uno de ellos dividido a su vez en cursos, formando un total de quince, perfectos para evaluaciones cuatrimestrales. A su vez la herramienta <strong>Dexway classroom teacher<\/strong> permite al tutor ofrecer una formaci\u00f3n <em>blended learning<\/em> en la que se combinen las clases presenciales con soluciones multimedia muy interactivas que fomenten la motivaci\u00f3n y participaci\u00f3n de los alumnos en la <strong>comunidad virtual<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1348 aligncenter\" src=\"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/06\/University-Labs-1024x683.jpg\" alt=\"University Labs\" width=\"1024\" height=\"683\" \/><\/p>\n<h3>BENEFICIOS<\/h3>\n<p>Al utilizar la <strong>soluci\u00f3n educativa para el sector educativo Dexway<\/strong> la universidad logr\u00f3 obtener los siguientes beneficios:<\/p>\n<ul>\n<li>Alcanzar objetivos por encima de la media establecida seg\u00fan los niveles de referencia (MCERL, TOEFL, ESOL).<\/li>\n<li>Aumentar el n\u00famero de alumnos matriculados en los cursos de idiomas.<\/li>\n<li>Ofrecer una ense\u00f1anza personalizada y flexible en l\u00ednea con las necesidades de los alumnos de educaci\u00f3n superior.<\/li>\n<li>Favorecer un aprendizaje aplicado de idiomas enfocado al futuro laboral del alumno.<\/li>\n<li>Fomentar habilidades necesarias en el siglo XXI para que los alumnos se desenvuelvan con \u00e9xito en un entorno globalizado e interconectado.<\/li>\n<\/ul>\n<h2>Sacando partido a la tecnolog\u00eda Dexway<\/h2>\n<p>Los centros de ense\u00f1anza superior actuales son conscientes de la importancia de ofrecer un plan de estudios de calidad, personalizado, flexible y que prepare al alumno para su actividad profesional futura dentro de un contexto globalizado. Utilizando la <strong>tecnolog\u00eda Dexway<\/strong> la universidad pudo crear una oferta en idiomas m\u00e1s rica e innovadora. A su vez los estudiantes accedieron a cursos flexibles y personalizados, en los que el desarrollo de las diferentes competencias ling\u00fc\u00edsticas trabajaba aspectos espec\u00edficos de su futura actividad laboral. Finalmente la <strong>plataforma educativa<\/strong>, favoreci\u00f3 una formaci\u00f3n <em>blended learnig<\/em> m\u00e1s participativa en la que los estudiantes pudieron compartir tanto experiencias de aprendizaje como personales, fortaleci\u00e9ndose de este modo los lazos de la comunidad.<\/p>\n<h2>Incorporando soluciones de \u00e9xito<\/h2>\n<p><strong><a href=\"http:\/\/www.dexway.com\/\">Dexway<\/a><\/strong>, la divisi\u00f3n especializada en idiomas de <a href=\"https:\/\/www.cae.net\/\"><strong>Computer Aided Elearning (CAE)<\/strong><\/a>, es la compa\u00f1\u00eda l\u00edder internacional en el desarrollo de soluciones tecnol\u00f3gicas para la formaci\u00f3n en idiomas. En nuestros 34 a\u00f1os de experiencia, hemos formado a m\u00e1s de 2 millones de alumnos en todo el mundo y generado m\u00e1s de 3000 horas de contenidos interactivos de idiomas. Los <strong>cursos online Dexway Academy (V3)<\/strong> siguen una metodolog\u00eda basada en la participaci\u00f3n del alumno en contextos que recrean situaciones comunicativas reales, de forma que pueda aplicar de manera activa los conocimientos adquiridos desde un primer momento. Nuestro equipo de pedagogos ha desarrollado un plan estructurado de lecciones que favorecen un aprendizaje progresivo y flexible seg\u00fan el ritmo que vaya marcando el propio alumno e incluyen una serie de actividades multimedia pensadas para estudiantes nativo digitales. Por otro lado, <strong>Dexway classroom teacher<\/strong> permite incorporar de forma sencilla y progresiva el <em>blended learning<\/em> dentro del aula, de modo que los alumnos puedan continuar su formaci\u00f3n despu\u00e9s de las clases presenciales y el tutor lleve un seguimiento en tiempo real del avance de sus estudiantes en cada uno de los temas.<\/p>\n<h2>Comprender los beneficios<\/h2>\n<p>Despu\u00e9s de incorporar el <strong>m\u00e9todo de idiomas Dexway<\/strong>, la universidad pudo constatar la ventajas de incorporar un <em>partner<\/em> especializado en la ense\u00f1anza <em>blended learning<\/em> de idiomas. Las competencias en las diferentes lenguas de los estudiantes aumentaron notablemente seg\u00fan los est\u00e1ndares oficiales (TOEFL, ESOL Y MCERL), la participaci\u00f3n de<\/p>\n<p>los estudiantes en los cursos de idiomas aument\u00f3 respecto a promociones anteriores, los tutores pudieron enriquecer sus clases con actividades multimedia a medida, el seguimiento a tiempo real permiti\u00f3 dise\u00f1ar un plan de estudio m\u00e1s alineado con las necesidades del alumno y, finalmente, la plataforma educativa favoreci\u00f3 la creaci\u00f3n de una comunidad virtual que posibilit\u00f3 la comunicaci\u00f3n y cooperaci\u00f3n entre los alumnos.<\/p>\n<p>Pincha aqu\u00ed para descargarte nuestro Caso de \u00c9xito: <a href=\"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/07\/Caso-de-exito-educacion-superior.pdf\" target=\"_blank\" rel=\"noopener\">Caso de exito educacion superior<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL RETO La necesidad part\u00eda de una universidad p\u00fablica con vocaci\u00f3n internacional, que apuesta por el conocimiento y la innovaci\u00f3n para lograr sus objetivos de calidad en la docencia. Est\u00e1 universidad imparte 81 titulaciones de grado, m\u00e1steres, doctorados y seminarios, muchos de ellos en lengua inglesa, recibe una media de 5000 estudiantes internacionales cada a\u00f1o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-cae"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soluci\u00f3n educativa para educaci\u00f3n superior<\/title>\n<meta name=\"description\" content=\"Caso de \u00e9xito en el que se describe la soluci\u00f3n educativa dise\u00f1ada por CAE para el sector educativo superior, una universidad con perfil internacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soluci\u00f3n educativa para educaci\u00f3n superior\" \/>\n<meta property=\"og:description\" content=\"Caso de \u00e9xito en el que se describe la soluci\u00f3n educativa dise\u00f1ada por CAE para el sector educativo superior, una universidad con perfil internacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"CAE Computer Aided E-learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elearning.cae\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-24T09:59:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-28T13:35:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/06\/University-Labs-e1437125810128.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:site\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/\"},\"author\":{\"name\":\"Communication\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"headline\":\"Una soluci\u00f3n educativa para una universidad p\u00fablica internacional\",\"datePublished\":\"2015-07-24T09:59:10+00:00\",\"dateModified\":\"2025-11-28T13:35:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/\"},\"wordCount\":862,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/University-Labs-e1437125810128.jpg\",\"articleSection\":[\"Blog CAE\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/\",\"name\":\"Soluci\u00f3n educativa para educaci\u00f3n superior\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/University-Labs-e1437125810128.jpg\",\"datePublished\":\"2015-07-24T09:59:10+00:00\",\"dateModified\":\"2025-11-28T13:35:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"description\":\"Caso de \u00e9xito en el que se describe la soluci\u00f3n educativa dise\u00f1ada por CAE para el sector educativo superior, una universidad con perfil internacional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/University-Labs-e1437125810128.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/University-Labs-e1437125810128.jpg\",\"width\":900,\"height\":600,\"caption\":\"Aulas en red\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una soluci\u00f3n educativa para una universidad p\u00fablica internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\",\"name\":\"CAE Computer Aided E-learning\",\"description\":\"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cae.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\",\"name\":\"Communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"caption\":\"Communication\"},\"sameAs\":[\"http:\\\/\\\/www.cae.net\"],\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/author\\\/carmen-d-rosell-e-learning-specialist\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soluci\u00f3n educativa para educaci\u00f3n superior","description":"Caso de \u00e9xito en el que se describe la soluci\u00f3n educativa dise\u00f1ada por CAE para el sector educativo superior, una universidad con perfil internacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Soluci\u00f3n educativa para educaci\u00f3n superior","og_description":"Caso de \u00e9xito en el que se describe la soluci\u00f3n educativa dise\u00f1ada por CAE para el sector educativo superior, una universidad con perfil internacional.","og_url":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/","og_site_name":"CAE Computer Aided E-learning","article_publisher":"https:\/\/www.facebook.com\/elearning.cae","article_published_time":"2015-07-24T09:59:10+00:00","article_modified_time":"2025-11-28T13:35:09+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/06\/University-Labs-e1437125810128.jpg","type":"image\/jpeg"}],"author":"Communication","twitter_card":"summary_large_image","twitter_creator":"@elearning_cae","twitter_site":"@elearning_cae","twitter_misc":{"Escrito por":"Communication","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#article","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/"},"author":{"name":"Communication","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"headline":"Una soluci\u00f3n educativa para una universidad p\u00fablica internacional","datePublished":"2015-07-24T09:59:10+00:00","dateModified":"2025-11-28T13:35:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/"},"wordCount":862,"commentCount":0,"image":{"@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/06\/University-Labs-e1437125810128.jpg","articleSection":["Blog CAE"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/","url":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/","name":"Soluci\u00f3n educativa para educaci\u00f3n superior","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#primaryimage"},"image":{"@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/06\/University-Labs-e1437125810128.jpg","datePublished":"2015-07-24T09:59:10+00:00","dateModified":"2025-11-28T13:35:09+00:00","author":{"@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"description":"Caso de \u00e9xito en el que se describe la soluci\u00f3n educativa dise\u00f1ada por CAE para el sector educativo superior, una universidad con perfil internacional.","breadcrumb":{"@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#primaryimage","url":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/06\/University-Labs-e1437125810128.jpg","contentUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/06\/University-Labs-e1437125810128.jpg","width":900,"height":600,"caption":"Aulas en red"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cae.net\/es\/desarrollo-de-una-solucion-educativa-para-una-universidad-publica-con-perfil-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cae.net\/es\/"},{"@type":"ListItem","position":2,"name":"Una soluci\u00f3n educativa para una universidad p\u00fablica internacional"}]},{"@type":"WebSite","@id":"https:\/\/www.cae.net\/es\/#website","url":"https:\/\/www.cae.net\/es\/","name":"CAE Computer Aided E-learning","description":"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cae.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad","name":"Communication","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","caption":"Communication"},"sameAs":["http:\/\/www.cae.net"],"url":"https:\/\/www.cae.net\/es\/author\/carmen-d-rosell-e-learning-specialist\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/1519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/comments?post=1519"}],"version-history":[{"count":0,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/1519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/media\/1348"}],"wp:attachment":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/media?parent=1519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/categories?post=1519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/tags?post=1519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}