{"id":3259,"date":"2015-12-28T09:26:52","date_gmt":"2015-12-28T09:26:52","guid":{"rendered":"https:\/\/www.cae.net\/?p=3259"},"modified":"2026-01-09T15:55:39","modified_gmt":"2026-01-09T14:55:39","slug":"flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas","status":"publish","type":"post","link":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/","title":{"rendered":"Flipped classroom, el nuevo modelo pedag\u00f3gico para aprender idiomas"},"content":{"rendered":"<p>El <strong>flipped classroom<\/strong> o <strong>aula inversa<\/strong> se est\u00e1 convirtiendo en el <a href=\"http:\/\/www.dexway.com\/\"><strong>modelo pedag\u00f3gico por excelencia<\/strong> para la <strong>ense\u00f1anza de idiomas<\/strong><\/a> en las aulas dentro del <strong>sector educativo<\/strong>. Esta <strong>innovadora metodolog\u00eda,<\/strong> permite a los profesores centrarse mucho m\u00e1s en ayudar a sus alumnos a <strong>desarrollar<\/strong> sus <strong>habilidades de comunicaci\u00f3n<\/strong>, fundamentales para el <strong>dominio<\/strong> de un <strong>idioma.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3263 aligncenter\" src=\"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas-1024x572.jpg\" alt=\"flipped classroom el nuevo modelo pedagogico para aprender idiomas\" width=\"1024\" height=\"572\" srcset=\"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas-1024x572.jpg 1024w, https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas-400x223.jpg 400w, https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas-300x167.jpg 300w, https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg 1075w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>3 ventajas del flipped classroom para ense\u00f1ar y aprender ingl\u00e9s<\/h2>\n<p>&nbsp;<\/p>\n<h3>#1 Mayor dedicaci\u00f3n del alumno hacia el aprendizaje del idioma<\/h3>\n<p>Con <a href=\"https:\/\/www.cae.net\/methodology\/\">este <strong>m\u00e9todo<\/strong><\/a> los <strong>estudiantes<\/strong> <strong>dedican<\/strong> mucho <strong>m\u00e1s tiempo<\/strong> al <strong>aprendizaje<\/strong> del<strong> idioma<\/strong>,<strong> interactuando<\/strong> con la base del mismo a trav\u00e9s de todas las actividades que realiza de <strong>forma individual<\/strong> y en <strong>profundidad<\/strong> fuera del aula. A trav\u00e9s de un <strong>software educativo<\/strong> y <strong>contenidos online complementarios<\/strong> el alumno se sumerge en <strong>profundidad<\/strong> en la nueva lengua, avanzando a su ritmo.<\/p>\n<h3>#2 Mayor atenci\u00f3n del profesor a la diversidad del aula<\/h3>\n<p>Con el <strong>flipped classroom<\/strong> los <strong>educadores<\/strong> tienen mucho <strong>m\u00e1s tiempo<\/strong> de clase para <strong>dedicar <\/strong>a sus<strong> alumnos<\/strong>, cosa que con el m\u00e9todo tradicional aun queriendo no llegar\u00edan teniendo entre 20 y 30 alumnos en la clase en una hora. El tiempo dentro del aula una vez que los alumnos han avanzado en el conocimiento del idioma fuera de ella, es para ampliar informaci\u00f3n, resolver dudas y dedicar tiempo al estudiante. De esta forma el <strong>profesor<\/strong> puede <strong>llegar a muchos m\u00e1s alumnos<\/strong> independientemente de su ritmo de aprendizaje. Los profesores pueden adem\u00e1s <strong>incorporar nuevas actividades<\/strong> y <strong>ejercicios colaborativos en el aula<\/strong>, que antes no pod\u00edan por el tiempo limitado.<\/p>\n<h3>#3 La tecnolog\u00eda educativa al servicio del aprendizaje<\/h3>\n<p>Las <strong>clases de ingl\u00e9s<\/strong> con un libro de texto y los cl\u00e1sicos cds con los listenings se est\u00e1n quedando atr\u00e1s, no s\u00f3lo los alumnos rechazan cada vez m\u00e1s este m\u00e9todo sino que los profesores tambi\u00e9n reclaman una <strong>renovaci\u00f3n<\/strong>.\u00a0 De hecho una de las quejas frecuentes de los profesores de idiomas es que no tienen suficiente tiempo en el aula para practicar las <strong>habilidades comunicativas<\/strong>, es decir, el <strong>speaking,<\/strong> fundamental para dominar un idioma. Con la suma del<strong> flipped classroom<\/strong>, los <strong>softwares educativos<\/strong> y el <strong>formato blended learning<\/strong> el <strong>alumno<\/strong> est\u00e1 mucho <strong>m\u00e1s preparado<\/strong> a la hora de dar la clase por lo que puede practicar m\u00e1s esta habilidad. Adem\u00e1s el <strong>profesor<\/strong> tiene <strong>muchos recursos<\/strong> para practicar en clase a trav\u00e9s de v\u00eddeos, audios, <strong>actividades interactivas<\/strong> que hacen que el <strong>aprendizaje en el aula<\/strong> se mucho m\u00e1s <strong>eficaz<\/strong> implicando mucho m\u00e1s al estudiante.<\/p>\n<h2>El m\u00e9todo para aprender ingl\u00e9s que realmente funciona<\/h2>\n<p><strong>Aprender ingl\u00e9s<\/strong> es mucho <strong>m\u00e1s sencillo y atractivo<\/strong> para los estudiantes con este<strong> innovador m\u00e9todo<\/strong>. Los estudiantes pueden ver previamente y trabajar el material a su propio ritmo y de acuerdo con sus necesidades, mientras que los profesores pueden <strong>estructurar<\/strong> el tiempo de sus clases para <strong>optimizar<\/strong> la atenci\u00f3n individualizada a cada uno de sus alumnos. Todo ello en un entorno que refuerza el aprendizaje.<\/p>\n<p>El <strong>blended learning<\/strong> o <strong>hybrid learning<\/strong>, ya no es el futuro de la educaci\u00f3n sino el <strong>presente<\/strong> de la <strong>educaci\u00f3n<\/strong>. El apoyo de profesores y estudiantes en la <strong>tecnolog\u00eda e-learning<\/strong> a trav\u00e9s de <strong>contenidos digitales<\/strong> es una <strong>ventaja competitiva<\/strong> para los <strong>centros educativos<\/strong> que adem\u00e1s asegura en la mayor\u00eda de los casos el <strong>\u00e9xito del aprendizaje de un idioma<\/strong>. La formaci\u00f3n cara a cara o la formaci\u00f3n presencial no debe desaparecer, pero si enriquecerse gracias a estas nuevas tendencias que permiten una mayor explotaci\u00f3n y optimizaci\u00f3n del tiempo en el aula.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El flipped classroom o aula inversa se est\u00e1 convirtiendo en el modelo pedag\u00f3gico por excelencia para la ense\u00f1anza de idiomas en las aulas dentro del sector educativo. Esta innovadora metodolog\u00eda, permite a los profesores centrarse mucho m\u00e1s en ayudar a sus alumnos a desarrollar sus habilidades de comunicaci\u00f3n, fundamentales para el dominio de un idioma. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117],"tags":[],"class_list":["post-3259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-idiomas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flipped classroom el mejor m\u00e9todo para ense\u00f1ar\u00a0idiomas<\/title>\n<meta name=\"description\" content=\"El flipped classroom\u00a0o aula inversa se est\u00e1 convirtiendo en el modelo pedag\u00f3gico por excelencia para la ense\u00f1anza de idiomas en las aulas\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flipped classroom el mejor m\u00e9todo para ense\u00f1ar\u00a0idiomas\" \/>\n<meta property=\"og:description\" content=\"El flipped classroom\u00a0o aula inversa se est\u00e1 convirtiendo en el modelo pedag\u00f3gico por excelencia para la ense\u00f1anza de idiomas en las aulas\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/\" \/>\n<meta property=\"og:site_name\" content=\"CAE Computer Aided E-learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elearning.cae\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-28T09:26:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-09T14:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1075\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:site\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/\"},\"author\":{\"name\":\"Communication\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"headline\":\"Flipped classroom, el nuevo modelo pedag\u00f3gico para aprender idiomas\",\"datePublished\":\"2015-12-28T09:26:52+00:00\",\"dateModified\":\"2026-01-09T14:55:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/\"},\"wordCount\":625,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg\",\"articleSection\":[\"Cursos de Idiomas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/\",\"name\":\"Flipped classroom el mejor m\u00e9todo para ense\u00f1ar\u00a0idiomas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg\",\"datePublished\":\"2015-12-28T09:26:52+00:00\",\"dateModified\":\"2026-01-09T14:55:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"description\":\"El flipped classroom\u00a0o aula inversa se est\u00e1 convirtiendo en el modelo pedag\u00f3gico por excelencia para la ense\u00f1anza de idiomas en las aulas\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg\",\"width\":1075,\"height\":600,\"caption\":\"flipped classroom el nuevo modelo pedagogico para aprender idiomas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flipped classroom, el nuevo modelo pedag\u00f3gico para aprender idiomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\",\"name\":\"CAE Computer Aided E-learning\",\"description\":\"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cae.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\",\"name\":\"Communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"caption\":\"Communication\"},\"sameAs\":[\"http:\\\/\\\/www.cae.net\"],\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/author\\\/carmen-d-rosell-e-learning-specialist\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flipped classroom el mejor m\u00e9todo para ense\u00f1ar\u00a0idiomas","description":"El flipped classroom\u00a0o aula inversa se est\u00e1 convirtiendo en el modelo pedag\u00f3gico por excelencia para la ense\u00f1anza de idiomas en las aulas\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/","og_locale":"es_ES","og_type":"article","og_title":"Flipped classroom el mejor m\u00e9todo para ense\u00f1ar\u00a0idiomas","og_description":"El flipped classroom\u00a0o aula inversa se est\u00e1 convirtiendo en el modelo pedag\u00f3gico por excelencia para la ense\u00f1anza de idiomas en las aulas\u00a0","og_url":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/","og_site_name":"CAE Computer Aided E-learning","article_publisher":"https:\/\/www.facebook.com\/elearning.cae","article_published_time":"2015-12-28T09:26:52+00:00","article_modified_time":"2026-01-09T14:55:39+00:00","og_image":[{"width":1075,"height":600,"url":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg","type":"image\/jpeg"}],"author":"Communication","twitter_card":"summary_large_image","twitter_creator":"@elearning_cae","twitter_site":"@elearning_cae","twitter_misc":{"Escrito por":"Communication","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#article","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/"},"author":{"name":"Communication","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"headline":"Flipped classroom, el nuevo modelo pedag\u00f3gico para aprender idiomas","datePublished":"2015-12-28T09:26:52+00:00","dateModified":"2026-01-09T14:55:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/"},"wordCount":625,"commentCount":0,"image":{"@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg","articleSection":["Cursos de Idiomas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/","url":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/","name":"Flipped classroom el mejor m\u00e9todo para ense\u00f1ar\u00a0idiomas","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#primaryimage"},"image":{"@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg","datePublished":"2015-12-28T09:26:52+00:00","dateModified":"2026-01-09T14:55:39+00:00","author":{"@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"description":"El flipped classroom\u00a0o aula inversa se est\u00e1 convirtiendo en el modelo pedag\u00f3gico por excelencia para la ense\u00f1anza de idiomas en las aulas\u00a0","breadcrumb":{"@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#primaryimage","url":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg","contentUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2015\/12\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas.jpg","width":1075,"height":600,"caption":"flipped classroom el nuevo modelo pedagogico para aprender idiomas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cae.net\/es\/flipped-classroom-el-nuevo-modelo-pedagogico-para-aprender-idiomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cae.net\/es\/"},{"@type":"ListItem","position":2,"name":"Flipped classroom, el nuevo modelo pedag\u00f3gico para aprender idiomas"}]},{"@type":"WebSite","@id":"https:\/\/www.cae.net\/es\/#website","url":"https:\/\/www.cae.net\/es\/","name":"CAE Computer Aided E-learning","description":"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cae.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad","name":"Communication","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","caption":"Communication"},"sameAs":["http:\/\/www.cae.net"],"url":"https:\/\/www.cae.net\/es\/author\/carmen-d-rosell-e-learning-specialist\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/3259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/comments?post=3259"}],"version-history":[{"count":0,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/3259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/media\/3263"}],"wp:attachment":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/media?parent=3259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/categories?post=3259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/tags?post=3259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}