{"id":6919,"date":"2016-10-12T11:00:04","date_gmt":"2016-10-12T11:00:04","guid":{"rendered":"https:\/\/www.cae.net\/?p=6919"},"modified":"2025-11-21T13:24:04","modified_gmt":"2025-11-21T12:24:04","slug":"blended-learning-futuro-centros-idiomas","status":"publish","type":"post","link":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/","title":{"rendered":"Blended learning: \u00bfel futuro de los centros de idiomas?"},"content":{"rendered":"<p>El<a href=\"http:\/\/www.dexway.com\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\"> aprendizaje de un idioma<\/a> es un proceso que dura de por vida. La actitud m\u00e1s inteligente que puede tener una persona o empresa es la de comprender que siempre hay algo nuevo que aprender del ingl\u00e9s, el franc\u00e9s, el alem\u00e1n, el ruso, el espa\u00f1ol\u2026Siempre existen conocimientos que adquirir para comunicarnos mejor en una lengua diferente y llegar as\u00ed a alcanzar nuestras metas y objetivos, cuando estos dependen del <strong>dominio de un idioma extranjero<\/strong>.<\/p>\n<p>Por eso existen <strong>metodolog\u00edas y soluciones\u00a0educativas<\/strong> que tambi\u00e9n <strong>evolucionan<\/strong> con el tiempo, porque incluso<strong> la propia ense\u00f1anza de idiomas necesita aprender y actualizarse<\/strong> permanentemente. De esta necesidad surge el <a href=\"http:\/\/www.dexway.com\/es\/blended-learning\/\" target=\"_blank\" rel=\"noopener noreferrer\">blended learning<\/a>, la <strong>combinaci\u00f3n<\/strong> de la<strong> ense\u00f1anza presencial<\/strong> con el <strong>aprendizaje\u00a0online<\/strong> o fuera del aula. El blended learning adem\u00e1s incorpora el uso de la tecnolog\u00eda como las <a href=\"http:\/\/www.dexway.com\/es\/blended-learning\/\" target=\"_blank\" rel=\"noopener noreferrer\">plataformas educativas<\/a> de gesti\u00f3n <strong>LMS<\/strong> y <strong>LCMS<\/strong>.<\/p>\n<p>Las <strong>plataformas educativas<\/strong>, son un elemento clave para modernizar la formaci\u00f3n en idiomas, para poder <strong>acceder al mundo del e-learning<\/strong> y <strong>enriquecer la formaci\u00f3n presencial<\/strong>, crear cursos y contenidos propios, automatizar la evaluaci\u00f3n y seguimiento de los alumnos, etc.<\/p>\n<p><a href=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-23622 size-full\" title=\"blended learning\" src=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg\" alt=\"blended learning languages\" width=\"1075\" height=\"600\" srcset=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg 1075w, https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion-980x547.jpg 980w, https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion-480x268.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1075px, 100vw\" \/><\/a><\/p>\n<h2>Un m\u00e9todo enfocado hacia\u00a0el alumno, posicionado como el futuro de los centros de idiomas<\/h2>\n<p>El <strong>\u00e9xito<\/strong> del <strong>blended learning<\/strong> es consecuencia entre otros factores de las <strong>ventajas<\/strong> que aportan los <a href=\"https:\/\/www.cae.net\/es\/lms-academias-de-idiomas-caracteristicas\/\" target=\"_blank\" rel=\"noopener noreferrer\">LMS\/LCMS<\/a> o <strong>plataformas educativas<\/strong>, ya que \u00a0convierten el blended learning en sencillo, eficaz, accesible, interactivo y controlable:<\/p>\n<h3>#1. Tan sencillo como tener un profesor particular<\/h3>\n<p>Para hacer una <strong>combinaci\u00f3n formativa perfecta<\/strong> entre lo <strong>presencial<\/strong> y el <strong>online, <\/strong>es necesaria una <strong>plataforma educativa<\/strong> para la gesti\u00f3n de aprendizaje, f\u00e1cil de usar intuitivamente por parte de todos los involucrados: administradores, tutores o empleados.<\/p>\n<h3>#2. Tan sencillo como eficaz, los LMS\/LCMS ofrecen resultados<\/h3>\n<p>A la hora de <strong>medir <\/strong>el<strong> rendimiento<\/strong> y<strong> evaluar <\/strong>a los<strong> alumnos<\/strong>, los LMS o plataformas educativas ayudan a los responsables de la formaci\u00f3n y profesores a valorar de forma <strong>automatizada<\/strong>, ahorrando mucho tiempo, los conocimientos adquiridos por los estudiantes, con un eficiente software de seguimiento y evaluaci\u00f3n\u00a0que garantiza la m\u00e1xima inmersi\u00f3n de aprendizaje de idiomas.<\/p>\n<h3>#3. Tan accesible como abrir un libro<\/h3>\n<p>El <strong>blended learning<\/strong> utiliza las <strong>plataformas de aprendizaje<\/strong> y gesti\u00f3n LMS y LCMS, con la gran ventaja de que alojan toda la<strong> informaci\u00f3n<\/strong>,<strong> recursos<\/strong> y <strong>materiales<\/strong> en un <strong>mismo sitio<\/strong>, en la <strong>nube<\/strong>, sin ocupar espacio y<strong> accesibles desde cualquier parte<\/strong> y <strong>desde cualquier dispositivo<\/strong>. Las plataformas educativas hacen que la informaci\u00f3n\u00a0est\u00e9 disponible siempre, con s\u00f3lo hacer un clic.<\/p>\n<h3>#4. Tan interactivo como las sesiones en el aula<\/h3>\n<p>Utilizando los LMS y LCMS para la formaci\u00f3n <strong>blended learning<\/strong> en un centro de idiomas, todo el equipo involucrado en la ense\u00f1anza (administradores, profesores y alumnos), puede <strong>aprender permanentemente<\/strong>, gracias a que se dispone de <strong>numerosas herramientas<\/strong> para<strong> conectarse<\/strong> en cualquier lugar y recibir sus feedback y evaluaciones en remoto. Adem\u00e1s las plataformas de aprendizaje incorporan otras funcionalidades muy \u00fatiles para la practica del idioma entre los alumnos y profesores y potenciar un aprendizaje social, como son los <strong>grupos de conversaci\u00f3n<\/strong>, las <strong>clases virtuales<\/strong> online y la <strong>comunidad de estudiantes<\/strong>.<\/p>\n<h3>#5. Tan controlable como una hoja de c\u00e1lculo<\/h3>\n<p>Otra de las ventajas de las <strong>plataformas educativas<\/strong> es que en todo momento<strong> facilitan informaci\u00f3n<\/strong> sobre el <strong>progreso<\/strong> de los alumnos o grupos de alumnos as\u00ed como de las deficiencias o puntos a trabajar en el aula. Tambi\u00e9n permiten<strong> programar <\/strong>las<strong> clases semanalmente<\/strong> y <strong>distribuir los contenidos, temas y objetivos<\/strong> a trabajar por sus estudiantes de forma sencilla,<\/p>\n<p>El <strong>blended learning<\/strong> no es el futuro sino el <strong>presente de la formaci\u00f3n de \u00e9xito<\/strong> en cualquier materia, pero en idiomas mucho m\u00e1s dada la flexibilidad que aporta a las academias de idiomas, centros de formaci\u00f3n, a sus profesores y estudiantes. Existen muchas combinaciones que dicen ser un formato blend de ense\u00f1anza, pero sin duda las <strong>plataformas educativas<\/strong> LMS\/LCMS son <strong>clave<\/strong> para<strong> impartir<\/strong> un <strong>blend de calidad<\/strong>, para<strong> ofrecer un valor a\u00f1adido<\/strong> a los estudiantes y sobre todo para <strong>seguir creciendo<\/strong> en el mundo de la ense\u00f1anza.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El aprendizaje de un idioma es un proceso que dura de por vida. La actitud m\u00e1s inteligente que puede tener una persona o empresa es la de comprender que siempre hay algo nuevo que aprender del ingl\u00e9s, el franc\u00e9s, el alem\u00e1n, el ruso, el espa\u00f1ol\u2026Siempre existen conocimientos que adquirir para comunicarnos mejor en una lengua [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[502,8],"tags":[],"class_list":["post-6919","post","type-post","status-publish","format-standard","hentry","category-blended-learning-es","category-blog-cae"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blended learning \u00bfel futuro de la ense\u00f1anza de idiomas?<\/title>\n<meta name=\"description\" content=\"El blended learning combinado con las plataformas de aprendizaje LMS\/LCMS permite a academias y centros de formaci\u00f3n en idiomas un crecimiento continuo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blended learning \u00bfel futuro de la ense\u00f1anza de idiomas?\" \/>\n<meta property=\"og:description\" content=\"El blended learning combinado con las plataformas de aprendizaje LMS\/LCMS permite a academias y centros de formaci\u00f3n en idiomas un crecimiento continuo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/\" \/>\n<meta property=\"og:site_name\" content=\"CAE Computer Aided E-learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elearning.cae\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-12T11:00:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T12:24:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1075\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:site\" content=\"@elearning_cae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/\"},\"author\":{\"name\":\"Communication\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"headline\":\"Blended learning: \u00bfel futuro de los centros de idiomas?\",\"datePublished\":\"2016-10-12T11:00:04+00:00\",\"dateModified\":\"2025-11-21T12:24:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/\"},\"wordCount\":705,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/blended-learning-educacion.jpg\",\"articleSection\":[\"Blended Learning\",\"Blog CAE\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/\",\"name\":\"Blended learning \u00bfel futuro de la ense\u00f1anza de idiomas?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/blended-learning-educacion.jpg\",\"datePublished\":\"2016-10-12T11:00:04+00:00\",\"dateModified\":\"2025-11-21T12:24:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\"},\"description\":\"El blended learning combinado con las plataformas de aprendizaje LMS\\\/LCMS permite a academias y centros de formaci\u00f3n en idiomas un crecimiento continuo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/blended-learning-educacion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cae.net\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/blended-learning-educacion.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/blended-learning-futuro-centros-idiomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blended learning: \u00bfel futuro de los centros de idiomas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/\",\"name\":\"CAE Computer Aided E-learning\",\"description\":\"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cae.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cae.net\\\/es\\\/#\\\/schema\\\/person\\\/f5f26dbaaa816ab827e859d1cda528ad\",\"name\":\"Communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g\",\"caption\":\"Communication\"},\"sameAs\":[\"http:\\\/\\\/www.cae.net\"],\"url\":\"https:\\\/\\\/www.cae.net\\\/es\\\/author\\\/carmen-d-rosell-e-learning-specialist\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blended learning \u00bfel futuro de la ense\u00f1anza de idiomas?","description":"El blended learning combinado con las plataformas de aprendizaje LMS\/LCMS permite a academias y centros de formaci\u00f3n en idiomas un crecimiento continuo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/","og_locale":"es_ES","og_type":"article","og_title":"Blended learning \u00bfel futuro de la ense\u00f1anza de idiomas?","og_description":"El blended learning combinado con las plataformas de aprendizaje LMS\/LCMS permite a academias y centros de formaci\u00f3n en idiomas un crecimiento continuo.","og_url":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/","og_site_name":"CAE Computer Aided E-learning","article_publisher":"https:\/\/www.facebook.com\/elearning.cae","article_published_time":"2016-10-12T11:00:04+00:00","article_modified_time":"2025-11-21T12:24:04+00:00","og_image":[{"width":1075,"height":600,"url":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg","type":"image\/jpeg"}],"author":"Communication","twitter_card":"summary_large_image","twitter_creator":"@elearning_cae","twitter_site":"@elearning_cae","twitter_misc":{"Escrito por":"Communication","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#article","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/"},"author":{"name":"Communication","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"headline":"Blended learning: \u00bfel futuro de los centros de idiomas?","datePublished":"2016-10-12T11:00:04+00:00","dateModified":"2025-11-21T12:24:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/"},"wordCount":705,"commentCount":0,"image":{"@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg","articleSection":["Blended Learning","Blog CAE"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/","url":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/","name":"Blended learning \u00bfel futuro de la ense\u00f1anza de idiomas?","isPartOf":{"@id":"https:\/\/www.cae.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#primaryimage"},"image":{"@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg","datePublished":"2016-10-12T11:00:04+00:00","dateModified":"2025-11-21T12:24:04+00:00","author":{"@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad"},"description":"El blended learning combinado con las plataformas de aprendizaje LMS\/LCMS permite a academias y centros de formaci\u00f3n en idiomas un crecimiento continuo.","breadcrumb":{"@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#primaryimage","url":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg","contentUrl":"https:\/\/www.cae.net\/wp-content\/uploads\/2016\/10\/blended-learning-educacion.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cae.net\/es\/blended-learning-futuro-centros-idiomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cae.net\/es\/"},{"@type":"ListItem","position":2,"name":"Blended learning: \u00bfel futuro de los centros de idiomas?"}]},{"@type":"WebSite","@id":"https:\/\/www.cae.net\/es\/#website","url":"https:\/\/www.cae.net\/es\/","name":"CAE Computer Aided E-learning","description":"Expertos en Elearning, Plataformas educativas, formaci\u00f3n en idiomas, contenidos  online y offline","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cae.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cae.net\/es\/#\/schema\/person\/f5f26dbaaa816ab827e859d1cda528ad","name":"Communication","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=mm&r=g","caption":"Communication"},"sameAs":["http:\/\/www.cae.net"],"url":"https:\/\/www.cae.net\/es\/author\/carmen-d-rosell-e-learning-specialist\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/6919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/comments?post=6919"}],"version-history":[{"count":0,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/posts\/6919\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/media?parent=6919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/categories?post=6919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cae.net\/es\/wp-json\/wp\/v2\/tags?post=6919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}